{"id":7413,"date":"2015-12-03T17:39:43","date_gmt":"2015-12-03T17:39:43","guid":{"rendered":"https:\/\/www.comparaonline.com.br\/blog\/?p=7413"},"modified":"2020-12-29T11:37:52","modified_gmt":"2020-12-29T14:37:52","slug":"lista-dos-carros-mais-e-menos-resistentes-uma-enchente","status":"publish","type":"post","link":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/","title":{"rendered":"Quais s\u00e3o os carros mais resistentes a uma enchente"},"content":{"rendered":"<p>Para saber quais s\u00e3o os carros mais e menos resistentes a uma enchente, o CESVI &#8211; Centro de Experimenta\u00e7\u00e3o e Seguran\u00e7a Vi\u00e1ria &#8211; publicou recentemente um ranking que classifica a capacidade de v\u00e1rios modelos e marcas de enfrentar uma situa\u00e7\u00e3o como esta.<\/p>\n<p>O \u00edndice dos carros mais e menos resistentes a uma enchente classifica os ve\u00edculos de acordo com os poss\u00edveis danos em fun\u00e7\u00e3o das caracter\u00edsticas mec\u00e2nicas e eletroeletr\u00f4nicas.<\/p>\n<p>Cada modelo recebe uma nota que varia entre 0,5 a 5 estrelas, sendo que quanto maior a nota, mais resist\u00eancia o carro apresenta para ao passar por uma enchente.<\/p>\n<p><strong>Conhe\u00e7a a lista dos carros mais e menos resistentes a uma enchente<\/strong><\/p>\n<p><a href=\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/rsz_enchentes.jpg\"><img loading='lazy' decoding='async' onerror='gen_methods.imageFailed(this)' loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7419\" src=\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/rsz_enchentes.jpg\" alt=\"enchentes\" width=\"520\" height=\"1482\"><\/a><\/p>\n<p>Como viram, o carro mais vem avaliado foi o Renault Influence, vers\u00e3o Dynamique CVT, ocupando o primeiro lugar do ranking. Em seguida se destaca o Nissan Sentra, o Chevrolet Cobalt e o Citroen C4.<\/p>\n<p>Aproveite para conferir <a href=\"https:\/\/www.comparaonline.com.br\/blog\/seguros\/seguro-auto\/2014\/01\/6-cuidados-necessarios-enfrentar-alagamentos\/\" target=\"_blank\" rel=\"noopener noreferrer\">6 cuidados necess\u00e1rios para enfrentar alagamentos<\/a>, <a href=\"https:\/\/www.comparaonline.com.br\/blog\/seguros\/seguro-auto\/2014\/03\/o-que-fazer-apos-passar-por-uma-rua-alagada\/\" target=\"_blank\" rel=\"noopener noreferrer\">o que voc\u00ea deve fazer ap\u00f3s passar por uma rua alagada<\/a> e <a href=\"https:\/\/www.comparaonline.com.br\/blog\/seguros\/seguro-auto\/2015\/02\/quando-o-seguro-protege-o-carro-contra-queda-de-arvores\/\" target=\"_blank\" rel=\"noopener noreferrer\">como o seguro atua no caso de uma \u00e1rvore cair no carro<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para saber quais s\u00e3o os carros mais e menos resistentes a uma enchente, o CESVI &#8211; Centro de Experimenta\u00e7\u00e3o e Seguran\u00e7a Vi\u00e1ria &#8211; publicou recentemente um ranking que classifica a capacidade de v\u00e1rios modelos e marcas de enfrentar uma situa\u00e7\u00e3o como esta.<\/p>\n","protected":false},"author":15,"featured_media":7416,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[714,715],"tags":[],"class_list":["post-7413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carros","category-seguro-auto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quais s\u00e3o os carros mais resistentes a uma enchente - ComparaOnline<\/title>\n<meta name=\"description\" content=\"Confira o ranking dos carros mais e menos resistentes a uma enchente. Se sua \u00e1rea tem bastante alagamento, essa informa\u00e7\u00e3o \u00e9 importante!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quais s\u00e3o os carros mais resistentes a uma enchente - ComparaOnline\" \/>\n<meta property=\"og:description\" content=\"Confira o ranking dos carros mais e menos resistentes a uma enchente. Se sua \u00e1rea tem bastante alagamento, essa informa\u00e7\u00e3o \u00e9 importante!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/\" \/>\n<meta property=\"og:site_name\" content=\"ComparaOnline\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comparabr\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-03T17:39:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-29T14:37:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/carro-enchente-azul.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"334\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pedro Da Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:site\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Da Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/\"},\"author\":{\"name\":\"Pedro Da Silva\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\"},\"headline\":\"Quais s\u00e3o os carros mais resistentes a uma enchente\",\"datePublished\":\"2015-12-03T17:39:43+00:00\",\"dateModified\":\"2020-12-29T14:37:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/\"},\"wordCount\":399,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/carro-enchente-azul.jpg\",\"articleSection\":[\"Carros\",\"Seguro Auto\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/\",\"name\":\"Quais s\u00e3o os carros mais resistentes a uma enchente - ComparaOnline\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/carro-enchente-azul.jpg\",\"datePublished\":\"2015-12-03T17:39:43+00:00\",\"dateModified\":\"2020-12-29T14:37:52+00:00\",\"description\":\"Confira o ranking dos carros mais e menos resistentes a uma enchente. Se sua \u00e1rea tem bastante alagamento, essa informa\u00e7\u00e3o \u00e9 importante!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#primaryimage\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/carro-enchente-azul.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/carro-enchente-azul.jpg\",\"width\":500,\"height\":334},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.comparaonline.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quais s\u00e3o os carros mais resistentes a uma enchente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"name\":\"ComparaOnline\",\"description\":\"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros\",\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\",\"name\":\"Compara\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"width\":161,\"height\":35,\"caption\":\"Compara\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/comparabr\",\"https:\/\/x.com\/compara_brasil\",\"https:\/\/www.instagram.com\/compara_brasil\/\",\"https:\/\/www.linkedin.com\/company\/compara\/\",\"https:\/\/www.youtube.com\/c\/ComparaBrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\",\"name\":\"Pedro Da Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"caption\":\"Pedro Da Silva\"},\"description\":\"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.\",\"sameAs\":[\"http:\/\/usuario.ge\/nerico\"],\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quais s\u00e3o os carros mais resistentes a uma enchente - ComparaOnline","description":"Confira o ranking dos carros mais e menos resistentes a uma enchente. Se sua \u00e1rea tem bastante alagamento, essa informa\u00e7\u00e3o \u00e9 importante!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/","og_locale":"pt_BR","og_type":"article","og_title":"Quais s\u00e3o os carros mais resistentes a uma enchente - ComparaOnline","og_description":"Confira o ranking dos carros mais e menos resistentes a uma enchente. Se sua \u00e1rea tem bastante alagamento, essa informa\u00e7\u00e3o \u00e9 importante!","og_url":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/","og_site_name":"ComparaOnline","article_publisher":"https:\/\/www.facebook.com\/comparabr","article_published_time":"2015-12-03T17:39:43+00:00","article_modified_time":"2020-12-29T14:37:52+00:00","og_image":[{"width":500,"height":334,"url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/carro-enchente-azul.jpg","type":"image\/jpeg"}],"author":"Pedro Da Silva","twitter_card":"summary_large_image","twitter_creator":"@compara_brasil","twitter_site":"@compara_brasil","twitter_misc":{"Escrito por":"Pedro Da Silva","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#article","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/"},"author":{"name":"Pedro Da Silva","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f"},"headline":"Quais s\u00e3o os carros mais resistentes a uma enchente","datePublished":"2015-12-03T17:39:43+00:00","dateModified":"2020-12-29T14:37:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/"},"wordCount":399,"commentCount":0,"publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/carro-enchente-azul.jpg","articleSection":["Carros","Seguro Auto"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/","url":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/","name":"Quais s\u00e3o os carros mais resistentes a uma enchente - ComparaOnline","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#primaryimage"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/carro-enchente-azul.jpg","datePublished":"2015-12-03T17:39:43+00:00","dateModified":"2020-12-29T14:37:52+00:00","description":"Confira o ranking dos carros mais e menos resistentes a uma enchente. Se sua \u00e1rea tem bastante alagamento, essa informa\u00e7\u00e3o \u00e9 importante!","breadcrumb":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#primaryimage","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/carro-enchente-azul.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/12\/carro-enchente-azul.jpg","width":500,"height":334},{"@type":"BreadcrumbList","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/seguro-auto\/lista-dos-carros-mais-e-menos-resistentes-uma-enchente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comparaonline.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Quais s\u00e3o os carros mais resistentes a uma enchente"}]},{"@type":"WebSite","@id":"https:\/\/www.comparaonline.com.br\/blog\/#website","url":"https:\/\/www.comparaonline.com.br\/blog\/","name":"ComparaOnline","description":"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros","publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization","name":"Compara","url":"https:\/\/www.comparaonline.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","width":161,"height":35,"caption":"Compara"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/comparabr","https:\/\/x.com\/compara_brasil","https:\/\/www.instagram.com\/compara_brasil\/","https:\/\/www.linkedin.com\/company\/compara\/","https:\/\/www.youtube.com\/c\/ComparaBrasil"]},{"@type":"Person","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f","name":"Pedro Da Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","caption":"Pedro Da Silva"},"description":"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.","sameAs":["http:\/\/usuario.ge\/nerico"],"url":"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/7413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/comments?post=7413"}],"version-history":[{"count":3,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/7413\/revisions"}],"predecessor-version":[{"id":19106,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/7413\/revisions\/19106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media\/7416"}],"wp:attachment":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media?parent=7413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/categories?post=7413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/tags?post=7413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}