{"id":5504,"date":"2015-06-22T10:00:25","date_gmt":"2015-06-22T10:00:25","guid":{"rendered":"http:\/\/blog.comparaonline.com.br\/?p=5504"},"modified":"2018-11-14T08:55:38","modified_gmt":"2018-11-14T10:55:38","slug":"indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014","status":"publish","type":"post","link":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/","title":{"rendered":"Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014"},"content":{"rendered":"<p>O n\u00famero de indeniza\u00e7\u00f5es pagas pelo DPVAT, o <strong><a title=\"Contrate o seguro do seu carro com Compara!\" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\">seguro de carro<\/a>\u00a0<\/strong>obrigat\u00f3rio, subiu 20% entre 2013 e 2014, de acordo com dados divulgados no in\u00edcio de mar\u00e7o deste ano pela seguradora L\u00edder, que \u00e9 respons\u00e1vel pelo servi\u00e7o. Em 2013, foram pagos cerca de 633 mil indeniza\u00e7\u00f5es. Em 2014, esse n\u00famero subiu para 736 mil, o que equivale a R$ 3,9 bilh\u00f5es.<\/p>\n<p>O que mais causou ressarcimentos foram os casos de invalidez. Eles foram respons\u00e1veis por 78% dos registros do ano, um total de quase 600 mil indeniza\u00e7\u00f5es. Nos demais casos, as indeniza\u00e7\u00f5es do <a title=\"Fa\u00e7a o seguro do seu carro com Compara!\" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"><strong>seguro do auto<\/strong><\/a> foram relacionadas ao reembolso de despesas em hospitais, totalizando 15%, e casos de morte, totalizando 7%. Os casos de reembolso totalizaram pouco mais de 100 mil casos e os de morte, pouco mais de 50 mil casos.<\/p>\n<p>De acordo com o levantamento, aumentou em 34% o n\u00famero de indeniza\u00e7\u00f5es decorrentes de invalidez permanente. Isso representa uma diminui\u00e7\u00e3o em 14% no valor de indeniza\u00e7\u00f5es por reembolso de gastos m\u00e9dicos e decr\u00e9scimo de 5% nas indeniza\u00e7\u00f5es decorrentes de morte.<\/p>\n<p>Para a seguradora L\u00edder, o decr\u00e9scimo no n\u00famero de mortes est\u00e1 diretamente relacionado aos equipamentos de seguran\u00e7a atuais, como airbag, cinto de seguran\u00e7a, al\u00e9m da cria\u00e7\u00e3o de pol\u00edticas de seguran\u00e7a, como a diminui\u00e7\u00e3o da velocidade m\u00e1xima em diversas vias e a Lei Seca.<\/p>\n<p>A maioria dos motoristas que receberam indeniza\u00e7\u00e3o pelo <a title=\"Fa\u00e7a a cota\u00e7\u00e3o do seu seguro auto com Compara!\" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"><strong>seguro automotivo <\/strong><\/a>foram homens, que representaram um total de 75%. Al\u00e9m disso, os jovens representaram a maior parte dos indenizados: 24% tinham entre 18 e 24 anos.<\/p>\n<p>Cerca de R$ 3,8 bilh\u00f5es arrecadados pelo seguro obrigat\u00f3rio &#8211; o valor representa 45% do total &#8211; s\u00e3o doados ao Sistema \u00danico de Sa\u00fade (SUS). O dinheiro \u00e9 usado para custear o tratamento de v\u00edtimas de acidentes de tr\u00e2nsito. Para completar, cerca de 5% do valor arrecadado \u00e9 usado para a cria\u00e7\u00e3o de campanhas educativas do Departamento Nacional de Tr\u00e2nsito (Denatran).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O n\u00famero de indeniza\u00e7\u00f5es pagas pelo DPVAT, o seguro de carro\u00a0obrigat\u00f3rio, subiu 20% entre 2013 e 2014, de acordo com dados divulgados no in\u00edcio de mar\u00e7o deste ano pela seguradora L\u00edder, que \u00e9 respons\u00e1vel pelo servi\u00e7o. Em 2013, foram pagos cerca de 633 mil indeniza\u00e7\u00f5es. Em 2014, esse n\u00famero subiu para 736 mil, o que&#8230;<\/p>\n","protected":false},"author":15,"featured_media":5505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[714,715],"tags":[],"class_list":["post-5504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carros","category-seguro-auto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014 - ComparaOnline<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a os casos que mais originaram ressarcimentos pelo DPVAT.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014 - ComparaOnline\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a os casos que mais originaram ressarcimentos pelo DPVAT.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/\" \/>\n<meta property=\"og:site_name\" content=\"ComparaOnline\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comparabr\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-22T10:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-14T10:55:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/04\/DPVAT.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"319\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pedro Da Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:site\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Da Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/\"},\"author\":{\"name\":\"Pedro Da Silva\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\"},\"headline\":\"Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014\",\"datePublished\":\"2015-06-22T10:00:25+00:00\",\"dateModified\":\"2018-11-14T10:55:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/\"},\"wordCount\":532,\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/04\/DPVAT.jpg\",\"articleSection\":[\"Carros\",\"Seguro Auto\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/\",\"name\":\"Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014 - ComparaOnline\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/04\/DPVAT.jpg\",\"datePublished\":\"2015-06-22T10:00:25+00:00\",\"dateModified\":\"2018-11-14T10:55:38+00:00\",\"description\":\"Conhe\u00e7a os casos que mais originaram ressarcimentos pelo DPVAT.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#primaryimage\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/04\/DPVAT.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/04\/DPVAT.jpg\",\"width\":500,\"height\":319},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.comparaonline.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"name\":\"ComparaOnline\",\"description\":\"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros\",\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\",\"name\":\"Compara\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"width\":161,\"height\":35,\"caption\":\"Compara\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/comparabr\",\"https:\/\/x.com\/compara_brasil\",\"https:\/\/www.instagram.com\/compara_brasil\/\",\"https:\/\/www.linkedin.com\/company\/compara\/\",\"https:\/\/www.youtube.com\/c\/ComparaBrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\",\"name\":\"Pedro Da Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"caption\":\"Pedro Da Silva\"},\"description\":\"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.\",\"sameAs\":[\"http:\/\/usuario.ge\/nerico\"],\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014 - ComparaOnline","description":"Conhe\u00e7a os casos que mais originaram ressarcimentos pelo DPVAT.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/","og_locale":"pt_BR","og_type":"article","og_title":"Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014 - ComparaOnline","og_description":"Conhe\u00e7a os casos que mais originaram ressarcimentos pelo DPVAT.","og_url":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/","og_site_name":"ComparaOnline","article_publisher":"https:\/\/www.facebook.com\/comparabr","article_published_time":"2015-06-22T10:00:25+00:00","article_modified_time":"2018-11-14T10:55:38+00:00","og_image":[{"width":500,"height":319,"url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/04\/DPVAT.jpg","type":"image\/jpeg"}],"author":"Pedro Da Silva","twitter_card":"summary_large_image","twitter_creator":"@compara_brasil","twitter_site":"@compara_brasil","twitter_misc":{"Escrito por":"Pedro Da Silva","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#article","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/"},"author":{"name":"Pedro Da Silva","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f"},"headline":"Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014","datePublished":"2015-06-22T10:00:25+00:00","dateModified":"2018-11-14T10:55:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/"},"wordCount":532,"publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/04\/DPVAT.jpg","articleSection":["Carros","Seguro Auto"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/","url":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/","name":"Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014 - ComparaOnline","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#primaryimage"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/04\/DPVAT.jpg","datePublished":"2015-06-22T10:00:25+00:00","dateModified":"2018-11-14T10:55:38+00:00","description":"Conhe\u00e7a os casos que mais originaram ressarcimentos pelo DPVAT.","breadcrumb":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#primaryimage","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/04\/DPVAT.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2015\/04\/DPVAT.jpg","width":500,"height":319},{"@type":"BreadcrumbList","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/indenizacoes-pagas-pelo-dpvat-crescem-20-em-2014\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comparaonline.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Indeniza\u00e7\u00f5es pagas pelo DPVAT crescem 20% em 2014"}]},{"@type":"WebSite","@id":"https:\/\/www.comparaonline.com.br\/blog\/#website","url":"https:\/\/www.comparaonline.com.br\/blog\/","name":"ComparaOnline","description":"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros","publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization","name":"Compara","url":"https:\/\/www.comparaonline.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","width":161,"height":35,"caption":"Compara"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/comparabr","https:\/\/x.com\/compara_brasil","https:\/\/www.instagram.com\/compara_brasil\/","https:\/\/www.linkedin.com\/company\/compara\/","https:\/\/www.youtube.com\/c\/ComparaBrasil"]},{"@type":"Person","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f","name":"Pedro Da Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","caption":"Pedro Da Silva"},"description":"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.","sameAs":["http:\/\/usuario.ge\/nerico"],"url":"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/5504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5504"}],"version-history":[{"count":2,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/5504\/revisions"}],"predecessor-version":[{"id":14652,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/5504\/revisions\/14652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media\/5505"}],"wp:attachment":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}