{"id":3907,"date":"2014-10-27T15:19:47","date_gmt":"2014-10-27T15:19:47","guid":{"rendered":"http:\/\/blog.comparaonline.com.br\/?p=3907"},"modified":"2018-11-12T22:28:00","modified_gmt":"2018-11-13T00:28:00","slug":"carros-desatualizados-o-desconto-vale-pena","status":"publish","type":"post","link":"https:\/\/www.comparaonline.com.br\/blog\/carros\/carros-desatualizados-o-desconto-vale-pena\/","title":{"rendered":"Carros desatualizados: o desconto vale a pena?"},"content":{"rendered":"<p>O segundo semestre de cada ano costuma fazer sucesso entre quem curte autom\u00f3veis porque \u00e9 conhecido como a \u00e9poca em que novos modelos s\u00e3o lan\u00e7ados. Ao mesmo tempo, modelo novo \u00e0 venda \u00e9 sin\u00f4nimo de que o antigo est\u00e1 sendo oferecido com \u00f3timos descontos para que as lojas esvaziem o estoque. Mas vale a pena comprar um carro desatualizado?<\/p>\n<p>Em geral, o <a title=\"Encontre o seguro auto mais barato em apenas 3 minutos! \" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"><strong>seguro de carro<\/strong><\/a> para modelos desatualizados pode sair um pouco mais caro. Mas h\u00e1 diversos fatores para se levar em conta para n\u00e3o cair em armadilhas e escolher a melhor op\u00e7\u00e3o.<\/p>\n<p>J\u00e1 que quando um novo modelo est\u00e1 prestes a sair \u00e0 procura pelo antigo diminui, ele tende a ser desvalorizado. E essa desvaloriza\u00e7\u00e3o fica entre 15% e 20% de seu valor. Por isso, eles podem oferecer condi\u00e7\u00f5es mais vantajosas para compra, n\u00e3o apenas em descontos, mas tamb\u00e9m com taxas pagas e equipamentos adicionais.<\/p>\n<p>Outros gastos extras como<a title=\"Fa\u00e7a o seguro do seu carro com Compara!\" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"> <strong>seguro do auto<\/strong><\/a> depender\u00e3o do estado do carro e do seu ano. Em geral, quanto mais antigo ele for, mais caro deve ser o seguro, j\u00e1 que suas pe\u00e7as quebradas ou que precisam de reposi\u00e7\u00e3o tendem a ser mais dif\u00edceis de encontrar.<\/p>\n<p>Sobre os descontos que um carro desatualizado pode oferecer, a regra \u00e9 que os modelos mais caros e equipados ganham descontos maiores. Na pr\u00e1tica, um sed\u00e3 m\u00e9dio pode ter 10% de desconto, enquanto um carro popular tem m\u00e9dia de 5%. Esses valores podem servir como base, mas cada autom\u00f3vel pode apresentar uma realidade diferente.<\/p>\n<p>Outros fatores que podem ajudar a aumentar esse desconto \u00e9 o tamanho do estoque do carro desatualizado e, principalmente, se houve ou n\u00e3o muitas mudan\u00e7as em rela\u00e7\u00e3o ao novo modelo e ao seu novo pre\u00e7o de tabela. Se a nova vers\u00e3o n\u00e3o apresenta muita mudan\u00e7a e seu valor \u00e9 semelhante ao antigo, \u00e9 natural que o desconto n\u00e3o seja grande e o carro desatualizado n\u00e3o compense.<\/p>\n<p>Al\u00e9m de conhecer bem todas essas varia\u00e7\u00f5es de pre\u00e7o de tabela, novas funcionalidades do modelo novo e pre\u00e7o do <a title=\"Contrate o seguro do seu carro com Compara!\" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"><strong>seguro do autom\u00f3vel<\/strong><\/a>, o importante \u00e9 sempre fazer muita pesquisa e pechinchar.<\/p>\n<p>A pesquisa \u00e9 particularmente importante porque o pre\u00e7o de um autom\u00f3vel pode estar alto em uma concession\u00e1ria que est\u00e1 vendendo muito o modelo, enquanto outra loja pode estar vendendo pouco e, consequentemente, oferecendo melhores descontos.<\/p>\n<p>Por isso, a palavra-chave para saber se comprar um carro desatualizado vale a pena ou n\u00e3o \u00e9 fazer muita pesquisa e comparar suas vantagens, funcionalidades e pre\u00e7o comparado ao novo modelo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O segundo semestre de cada ano costuma fazer sucesso entre quem curte autom\u00f3veis porque \u00e9 conhecido como a \u00e9poca em que novos modelos s\u00e3o lan\u00e7ados. Ao mesmo tempo, modelo novo \u00e0 venda \u00e9 sin\u00f4nimo de que o antigo est\u00e1 sendo oferecido com \u00f3timos descontos para que as lojas esvaziem o estoque. Mas vale a pena&#8230;<\/p>\n","protected":false},"author":15,"featured_media":3908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[714,715],"tags":[],"class_list":["post-3907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carros","category-seguro-auto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carros desatualizados: o desconto vale a pena? - ComparaOnline<\/title>\n<meta name=\"description\" content=\"Os carros desatualizados oferecem descontos tentadores. Mas ser\u00e1 que vale a pena ter um carro assim?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comparaonline.com.br\/blog\/carros\/carros-desatualizados-o-desconto-vale-pena\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carros desatualizados: o desconto vale a pena? - ComparaOnline\" \/>\n<meta property=\"og:description\" content=\"Os carros desatualizados oferecem descontos tentadores. Mas ser\u00e1 que vale a pena ter um carro assim?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/\" \/>\n<meta property=\"og:site_name\" content=\"ComparaOnline\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comparabr\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-27T15:19:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-13T00:28:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/10\/gol-blog-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"290\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pedro Da Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:site\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Da Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/\"},\"author\":{\"name\":\"Pedro Da Silva\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\"},\"headline\":\"Carros desatualizados: o desconto vale a pena?\",\"datePublished\":\"2014-10-27T15:19:47+00:00\",\"dateModified\":\"2018-11-13T00:28:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/\"},\"wordCount\":636,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/10\/gol-blog-.jpg\",\"articleSection\":[\"Carros\",\"Seguro Auto\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/\",\"name\":\"Carros desatualizados: o desconto vale a pena? - ComparaOnline\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/10\/gol-blog-.jpg\",\"datePublished\":\"2014-10-27T15:19:47+00:00\",\"dateModified\":\"2018-11-13T00:28:00+00:00\",\"description\":\"Os carros desatualizados oferecem descontos tentadores. Mas ser\u00e1 que vale a pena ter um carro assim?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#primaryimage\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/10\/gol-blog-.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/10\/gol-blog-.jpg\",\"width\":435,\"height\":290},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.comparaonline.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carros desatualizados: o desconto vale a pena?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"name\":\"ComparaOnline\",\"description\":\"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros\",\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\",\"name\":\"Compara\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"width\":161,\"height\":35,\"caption\":\"Compara\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/comparabr\",\"https:\/\/x.com\/compara_brasil\",\"https:\/\/www.instagram.com\/compara_brasil\/\",\"https:\/\/www.linkedin.com\/company\/compara\/\",\"https:\/\/www.youtube.com\/c\/ComparaBrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\",\"name\":\"Pedro Da Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"caption\":\"Pedro Da Silva\"},\"description\":\"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.\",\"sameAs\":[\"http:\/\/usuario.ge\/nerico\"],\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carros desatualizados: o desconto vale a pena? - ComparaOnline","description":"Os carros desatualizados oferecem descontos tentadores. Mas ser\u00e1 que vale a pena ter um carro assim?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comparaonline.com.br\/blog\/carros\/carros-desatualizados-o-desconto-vale-pena\/","og_locale":"pt_BR","og_type":"article","og_title":"Carros desatualizados: o desconto vale a pena? - ComparaOnline","og_description":"Os carros desatualizados oferecem descontos tentadores. Mas ser\u00e1 que vale a pena ter um carro assim?","og_url":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/","og_site_name":"ComparaOnline","article_publisher":"https:\/\/www.facebook.com\/comparabr","article_published_time":"2014-10-27T15:19:47+00:00","article_modified_time":"2018-11-13T00:28:00+00:00","og_image":[{"width":435,"height":290,"url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/10\/gol-blog-.jpg","type":"image\/jpeg"}],"author":"Pedro Da Silva","twitter_card":"summary_large_image","twitter_creator":"@compara_brasil","twitter_site":"@compara_brasil","twitter_misc":{"Written by":"Pedro Da Silva","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#article","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/"},"author":{"name":"Pedro Da Silva","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f"},"headline":"Carros desatualizados: o desconto vale a pena?","datePublished":"2014-10-27T15:19:47+00:00","dateModified":"2018-11-13T00:28:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/"},"wordCount":636,"commentCount":0,"publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/10\/gol-blog-.jpg","articleSection":["Carros","Seguro Auto"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/","url":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/","name":"Carros desatualizados: o desconto vale a pena? - ComparaOnline","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#primaryimage"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/10\/gol-blog-.jpg","datePublished":"2014-10-27T15:19:47+00:00","dateModified":"2018-11-13T00:28:00+00:00","description":"Os carros desatualizados oferecem descontos tentadores. Mas ser\u00e1 que vale a pena ter um carro assim?","breadcrumb":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#primaryimage","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/10\/gol-blog-.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/10\/gol-blog-.jpg","width":435,"height":290},{"@type":"BreadcrumbList","@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/carros-desatualizados-o-desconto-vale-pena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comparaonline.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Carros desatualizados: o desconto vale a pena?"}]},{"@type":"WebSite","@id":"https:\/\/www.comparaonline.com.br\/blog\/#website","url":"https:\/\/www.comparaonline.com.br\/blog\/","name":"ComparaOnline","description":"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros","publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization","name":"Compara","url":"https:\/\/www.comparaonline.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","width":161,"height":35,"caption":"Compara"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/comparabr","https:\/\/x.com\/compara_brasil","https:\/\/www.instagram.com\/compara_brasil\/","https:\/\/www.linkedin.com\/company\/compara\/","https:\/\/www.youtube.com\/c\/ComparaBrasil"]},{"@type":"Person","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f","name":"Pedro Da Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","caption":"Pedro Da Silva"},"description":"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.","sameAs":["http:\/\/usuario.ge\/nerico"],"url":"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/3907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3907"}],"version-history":[{"count":2,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/3907\/revisions"}],"predecessor-version":[{"id":13760,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/3907\/revisions\/13760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media\/3908"}],"wp:attachment":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}