{"id":3408,"date":"2014-09-08T13:43:21","date_gmt":"2014-09-08T13:43:21","guid":{"rendered":"http:\/\/blog.comparaonline.com.br\/?p=3408"},"modified":"2018-11-12T22:51:49","modified_gmt":"2018-11-13T00:51:49","slug":"a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25","status":"publish","type":"post","link":"https:\/\/www.comparaonline.com.br\/blog\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/","title":{"rendered":"A Lei do Desmanche diminui o valor do seguro em 25%"},"content":{"rendered":"<p>A partir de 2015, empresas que trabalham com desmanche de ve\u00edculos dever\u00e3o atender \u00e0s novas exig\u00eancias. Em maio de 2014 foi sancionada a Lei Federal 12.977 que <strong>visa estabelecer regras mais r\u00edgidas para destrui\u00e7\u00e3o, desmonte, destino da sucata e pe\u00e7as usadas de ve\u00edculos.<\/strong> E a nova lei promete aliviar o bolso dos consumidores, pois ela deve baixar o\u00a0<a title=\"Conhe\u00e7a todos os pre\u00e7os do mercado em um \u00fanico lugar: Compara!\" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"><strong>seguro de carro<\/strong><\/a>\u00a0em 25%.<\/p>\n<p>No caso do seguro popular, que utiliza pe\u00e7as de segunda m\u00e3o, o seguro pode ter uma baixa de at\u00e9 30% quando comparado ao tradicional. A nova lei imp\u00f5e que empresas do setor devem se inscrever em \u00f3rg\u00e3os fazend\u00e1rios e o alvar\u00e1 de funcionamento deve ser registrado pelo Detran local e expedido por autoridades da cidade.<\/p>\n<p>O Contran (Conselho Nacional de Tr\u00e2nsito) \u00e9 o respons\u00e1vel por regular a execu\u00e7\u00e3o das novas normas. A lei tamb\u00e9m tem como objetivo combater desmanches que financiam a criminalidade. Ser\u00e1 poss\u00edvel fazer um cadastro p\u00fablico para consultar quais s\u00e3o as empresas regularizadas e sistema de rastreamento de toda desmontagem. <strong>Dessa forma, o motorista pode ter a certeza se a origem das pe\u00e7as \u00e9 leg\u00edtima.<\/strong><\/p>\n<p>Antes da lei, apenas S\u00e3o Paulo, Rio de Janeiro, Rio Grande do Sul e os munic\u00edpios de Campinas e Ribeir\u00e3o Preto possu\u00edam regras sobre o tema. Com a nova lei, o esperado \u00e9 que haja diminui\u00e7\u00e3o da viol\u00eancia no tr\u00e2nsito, melhoria na seguran\u00e7a p\u00fablica, redu\u00e7\u00e3o no pre\u00e7o de repara\u00e7\u00e3o, aumento de arrecada\u00e7\u00e3o de impostos e gera\u00e7\u00e3o de novos empregos.<\/p>\n<p>A redu\u00e7\u00e3o de furto e roubo \u00e9 not\u00f3ria na Argentina, que conta com uma lei semelhante desde 2003. L\u00e1, o \u00edndice de furto e roubo diminuiu 50% e isso trouxe efeitos favor\u00e1veis sobre a sinistralidade e, consequentemente, pre\u00e7o do\u00a0<a title=\"Confira qual \u00e9 o melhor seguro auto para o seu perfil. Op\u00e7\u00f5es personalizadas com Compara! \" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"><strong>seguro do auto<\/strong>.<\/a>\u00a0A redu\u00e7\u00e3o do valor do seguro, entretanto, depende da intensidade da fiscaliza\u00e7\u00e3o. E o consumidor tem papel essencial na aplica\u00e7\u00e3o correta da lei e para que seus objetivos sejam concretizados ao sempre exigir pe\u00e7as certificadas e com proced\u00eancia.<\/p>\n<p>Para ter \u00e0 sua disposi\u00e7\u00e3o uma \u00f3tima ferramenta durante o processo de contrata\u00e7\u00e3o do\u00a0<strong>seguro<\/strong>, visite o <a title=\"Fa\u00e7a a cota\u00e7\u00e3o do seu seguro auto online. \u00c9 r\u00e1pido e f\u00e1cil! \" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"><strong>Compara<\/strong><\/a> e compare as melhores op\u00e7\u00f5es do mercado para o seu perfil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de 2015, empresas que trabalham com desmanche de ve\u00edculos dever\u00e3o atender \u00e0s novas exig\u00eancias. Em maio de 2014 foi sancionada a Lei Federal 12.977 que visa estabelecer regras mais r\u00edgidas para destrui\u00e7\u00e3o, desmonte, destino da sucata e pe\u00e7as usadas de ve\u00edculos. E a nova lei promete aliviar o bolso dos consumidores, pois ela&#8230;<\/p>\n","protected":false},"author":15,"featured_media":3409,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[714,715],"tags":[],"class_list":["post-3408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carros","category-seguro-auto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Lei do Desmanche diminui o valor do seguro em 25% - ComparaOnline<\/title>\n<meta name=\"description\" content=\"A nova Lei do Desmanche pode trazer vantagens aos motoristas n\u00e3o apenas referente a seguran\u00e7a mas tamb\u00e9m ao bolso. Entenda o motivo nesse post!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comparaonline.com.br\/blog\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Lei do Desmanche diminui o valor do seguro em 25% - ComparaOnline\" \/>\n<meta property=\"og:description\" content=\"A nova Lei do Desmanche pode trazer vantagens aos motoristas n\u00e3o apenas referente a seguran\u00e7a mas tamb\u00e9m ao bolso. Entenda o motivo nesse post!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/\" \/>\n<meta property=\"og:site_name\" content=\"ComparaOnline\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comparabr\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-08T13:43:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-13T00:51:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/09\/rsz_a_lei_do_desmanche_diminui_o_valor_do_seguro_em_25pct.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pedro Da Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:site\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Da Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/\"},\"author\":{\"name\":\"Pedro Da Silva\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\"},\"headline\":\"A Lei do Desmanche diminui o valor do seguro em 25%\",\"datePublished\":\"2014-09-08T13:43:21+00:00\",\"dateModified\":\"2018-11-13T00:51:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/\"},\"wordCount\":592,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/09\/rsz_a_lei_do_desmanche_diminui_o_valor_do_seguro_em_25pct.jpg\",\"articleSection\":[\"Carros\",\"Seguro Auto\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/\",\"name\":\"A Lei do Desmanche diminui o valor do seguro em 25% - ComparaOnline\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/09\/rsz_a_lei_do_desmanche_diminui_o_valor_do_seguro_em_25pct.jpg\",\"datePublished\":\"2014-09-08T13:43:21+00:00\",\"dateModified\":\"2018-11-13T00:51:49+00:00\",\"description\":\"A nova Lei do Desmanche pode trazer vantagens aos motoristas n\u00e3o apenas referente a seguran\u00e7a mas tamb\u00e9m ao bolso. Entenda o motivo nesse post!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#primaryimage\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/09\/rsz_a_lei_do_desmanche_diminui_o_valor_do_seguro_em_25pct.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/09\/rsz_a_lei_do_desmanche_diminui_o_valor_do_seguro_em_25pct.jpg\",\"width\":435,\"height\":277},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.comparaonline.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Lei do Desmanche diminui o valor do seguro em 25%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"name\":\"ComparaOnline\",\"description\":\"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros\",\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\",\"name\":\"Compara\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"width\":161,\"height\":35,\"caption\":\"Compara\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/comparabr\",\"https:\/\/x.com\/compara_brasil\",\"https:\/\/www.instagram.com\/compara_brasil\/\",\"https:\/\/www.linkedin.com\/company\/compara\/\",\"https:\/\/www.youtube.com\/c\/ComparaBrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\",\"name\":\"Pedro Da Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"caption\":\"Pedro Da Silva\"},\"description\":\"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.\",\"sameAs\":[\"http:\/\/usuario.ge\/nerico\"],\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Lei do Desmanche diminui o valor do seguro em 25% - ComparaOnline","description":"A nova Lei do Desmanche pode trazer vantagens aos motoristas n\u00e3o apenas referente a seguran\u00e7a mas tamb\u00e9m ao bolso. Entenda o motivo nesse post!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comparaonline.com.br\/blog\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/","og_locale":"pt_BR","og_type":"article","og_title":"A Lei do Desmanche diminui o valor do seguro em 25% - ComparaOnline","og_description":"A nova Lei do Desmanche pode trazer vantagens aos motoristas n\u00e3o apenas referente a seguran\u00e7a mas tamb\u00e9m ao bolso. Entenda o motivo nesse post!","og_url":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/","og_site_name":"ComparaOnline","article_publisher":"https:\/\/www.facebook.com\/comparabr","article_published_time":"2014-09-08T13:43:21+00:00","article_modified_time":"2018-11-13T00:51:49+00:00","og_image":[{"width":435,"height":277,"url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/09\/rsz_a_lei_do_desmanche_diminui_o_valor_do_seguro_em_25pct.jpg","type":"image\/jpeg"}],"author":"Pedro Da Silva","twitter_card":"summary_large_image","twitter_creator":"@compara_brasil","twitter_site":"@compara_brasil","twitter_misc":{"Escrito por":"Pedro Da Silva","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#article","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/"},"author":{"name":"Pedro Da Silva","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f"},"headline":"A Lei do Desmanche diminui o valor do seguro em 25%","datePublished":"2014-09-08T13:43:21+00:00","dateModified":"2018-11-13T00:51:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/"},"wordCount":592,"commentCount":0,"publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/09\/rsz_a_lei_do_desmanche_diminui_o_valor_do_seguro_em_25pct.jpg","articleSection":["Carros","Seguro Auto"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/","url":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/","name":"A Lei do Desmanche diminui o valor do seguro em 25% - ComparaOnline","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#primaryimage"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/09\/rsz_a_lei_do_desmanche_diminui_o_valor_do_seguro_em_25pct.jpg","datePublished":"2014-09-08T13:43:21+00:00","dateModified":"2018-11-13T00:51:49+00:00","description":"A nova Lei do Desmanche pode trazer vantagens aos motoristas n\u00e3o apenas referente a seguran\u00e7a mas tamb\u00e9m ao bolso. Entenda o motivo nesse post!","breadcrumb":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#primaryimage","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/09\/rsz_a_lei_do_desmanche_diminui_o_valor_do_seguro_em_25pct.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/09\/rsz_a_lei_do_desmanche_diminui_o_valor_do_seguro_em_25pct.jpg","width":435,"height":277},{"@type":"BreadcrumbList","@id":"https:\/\/www.comparaonline.com.br\/blog\/amp\/carros\/a-lei-do-desmanche-diminui-o-valor-do-seguro-em-25\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comparaonline.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"A Lei do Desmanche diminui o valor do seguro em 25%"}]},{"@type":"WebSite","@id":"https:\/\/www.comparaonline.com.br\/blog\/#website","url":"https:\/\/www.comparaonline.com.br\/blog\/","name":"ComparaOnline","description":"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros","publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization","name":"Compara","url":"https:\/\/www.comparaonline.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","width":161,"height":35,"caption":"Compara"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/comparabr","https:\/\/x.com\/compara_brasil","https:\/\/www.instagram.com\/compara_brasil\/","https:\/\/www.linkedin.com\/company\/compara\/","https:\/\/www.youtube.com\/c\/ComparaBrasil"]},{"@type":"Person","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f","name":"Pedro Da Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","caption":"Pedro Da Silva"},"description":"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.","sameAs":["http:\/\/usuario.ge\/nerico"],"url":"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/3408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3408"}],"version-history":[{"count":2,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/3408\/revisions"}],"predecessor-version":[{"id":13814,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/3408\/revisions\/13814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media\/3409"}],"wp:attachment":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}