{"id":3275,"date":"2014-08-25T16:17:09","date_gmt":"2014-08-25T16:17:09","guid":{"rendered":"http:\/\/blog.comparaonline.com.br\/?p=3275"},"modified":"2018-11-12T22:54:18","modified_gmt":"2018-11-13T00:54:18","slug":"primeiro-carro-hidrogenio-sera-lancado-em-2015","status":"publish","type":"post","link":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/","title":{"rendered":"Primeiro  carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015"},"content":{"rendered":"<p>S\u00e3o temas importantes para quem dirige um carro: o <a title=\"Contrate o seu seguro auto com Compara! \" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"><strong>seguro automotivo<\/strong><\/a>, o design, resist\u00eancia e confiabilidade do ve\u00edculo, entre outros. Mas o combust\u00edvel e a contribui\u00e7\u00e3o dele para a polui\u00e7\u00e3o do meio ambiente tamb\u00e9m \u00e9 algo que preocupa v\u00e1rios de n\u00f3s &#8212; al\u00e9m do alto pre\u00e7o do \u00e1lcool e gasolina.<\/p>\n<p>De olho nas fontes renov\u00e1veis de combust\u00edvel veicular, <strong>a montadora japonesa Toyota saiu na frente e vai lan\u00e7ar em abril 2015 um sed\u00e3 movido a c\u00e9lulas de hidrog\u00eanio<\/strong>. Essa \u00e9 uma excelente not\u00edcia, n\u00e3o apenas para os ambientalistas, mas para todos n\u00f3s, que precisamos encontrar fontes de energia limpas e renov\u00e1veis.<\/p>\n<p>O hidrog\u00eanio n\u00e3o libera g\u00e1s carb\u00f4nico na atmosfera, ent\u00e3o n\u00e3o contribui para a polui\u00e7\u00e3o e para o efeito estufa, e pode ser produzido a partir de fontes renov\u00e1veis, como a energia solar e e\u00f3lica. O &#8220;abastecimento&#8221; do carro, chamado de &#8220;carga de hidrog\u00eanio&#8221;, dura apenas tr\u00eas minutos, e garante ao motorista combust\u00edvel suficiente para dirigir por 700 km.<\/p>\n<p>Parece bom demais para ser verdade. Mas est\u00e1 se tornando uma realidade. O carro ser\u00e1 vendido a cerca de US$70 mil, e ser\u00e1 lan\u00e7ado inicialmente no Jap\u00e3o e depois nos Estados Unidos e Europa. Sua fabrica\u00e7\u00e3o conta com subs\u00eddios do governo japon\u00eas, e o projeto de um carro a hidrog\u00eanio tamb\u00e9m est\u00e1 sendo desenvolvido por outra montadora do pa\u00eds: a Honda, que j\u00e1 lan\u00e7ou anteriormente um ve\u00edculo a hidrog\u00eanio, e est\u00e1 preparando novo lan\u00e7amento, tamb\u00e9m para 2015.<\/p>\n<p>O Jap\u00e3o deve instalar cerca de 100 postos para abastecimento de carros a hidrog\u00eanio nos pr\u00f3ximos anos. Inicialmente, apenas a cidade de T\u00f3quio e regi\u00e3o contar\u00e3o com postos desse tipo, por isso, a venda dos carros especiais come\u00e7ar\u00e1 por l\u00e1, e deve ser ampliada aos poucos por todo o Jap\u00e3o.<\/p>\n<p>As pesquisas est\u00e3o avan\u00e7ando muito nessa \u00e1rea e pode ser que, muito em breve, tenhamos a possibilidade de contar com esses ve\u00edculos e postos tamb\u00e9m aqui no Brasil.\u00a0Com um design moderno, o carro a hidrog\u00eanio se parece com um sed\u00e3 comum, com linhas modernas e &#8220;clean&#8221;, bem no estilo japon\u00eas.<\/p>\n<p>Informe-se sobre outros temas atuais da ind\u00fastria automobil\u00edstica no site <a title=\"As melhores op\u00e7\u00f5es de seguro auto voc\u00ea encontra com Compara! \" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"><strong>Compara<\/strong><\/a>, e aproveite para fazer uma cota\u00e7\u00e3o de <a title=\"Encontre o seguro do seu carro com um clique! \" href=\"https:\/\/www.comparaonline.com.br\/seguro-de-auto\" target=\"_blank\"><strong>seguro do auto<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o temas importantes para quem dirige um carro: o seguro automotivo, o design, resist\u00eancia e confiabilidade do ve\u00edculo, entre outros. Mas o combust\u00edvel e a contribui\u00e7\u00e3o dele para a polui\u00e7\u00e3o do meio ambiente tamb\u00e9m \u00e9 algo que preocupa v\u00e1rios de n\u00f3s &#8212; al\u00e9m do alto pre\u00e7o do \u00e1lcool e gasolina.<\/p>\n","protected":false},"author":15,"featured_media":3276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[714,715],"tags":[],"class_list":["post-3275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carros","category-seguro-auto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primeiro carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015 - ComparaOnline<\/title>\n<meta name=\"description\" content=\"O lan\u00e7amento do primeiro carro a hidrog\u00eanio foi anunciado para 2015 pela Toyota. Mas voc\u00ea sabe o que isso pode representar para o setor automotivo? Veja!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primeiro carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015 - ComparaOnline\" \/>\n<meta property=\"og:description\" content=\"O lan\u00e7amento do primeiro carro a hidrog\u00eanio foi anunciado para 2015 pela Toyota. Mas voc\u00ea sabe o que isso pode representar para o setor automotivo? Veja!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"ComparaOnline\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comparabr\" \/>\n<meta property=\"article:published_time\" content=\"2014-08-25T16:17:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-13T00:54:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/08\/104942-carro-a-hidrognio-da-toyota-ser-lanado-em-2015-1407768551.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pedro Da Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:site\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Da Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/\"},\"author\":{\"name\":\"Pedro Da Silva\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\"},\"headline\":\"Primeiro carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015\",\"datePublished\":\"2014-08-25T16:17:09+00:00\",\"dateModified\":\"2018-11-13T00:54:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/\"},\"wordCount\":621,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/08\/104942-carro-a-hidrognio-da-toyota-ser-lanado-em-2015-1407768551.jpg\",\"articleSection\":[\"Carros\",\"Seguro Auto\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/\",\"name\":\"Primeiro carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015 - ComparaOnline\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/08\/104942-carro-a-hidrognio-da-toyota-ser-lanado-em-2015-1407768551.jpg\",\"datePublished\":\"2014-08-25T16:17:09+00:00\",\"dateModified\":\"2018-11-13T00:54:18+00:00\",\"description\":\"O lan\u00e7amento do primeiro carro a hidrog\u00eanio foi anunciado para 2015 pela Toyota. Mas voc\u00ea sabe o que isso pode representar para o setor automotivo? Veja!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#primaryimage\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/08\/104942-carro-a-hidrognio-da-toyota-ser-lanado-em-2015-1407768551.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/08\/104942-carro-a-hidrognio-da-toyota-ser-lanado-em-2015-1407768551.jpg\",\"width\":435,\"height\":288},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.comparaonline.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primeiro carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"name\":\"ComparaOnline\",\"description\":\"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros\",\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\",\"name\":\"Compara\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"width\":161,\"height\":35,\"caption\":\"Compara\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/comparabr\",\"https:\/\/x.com\/compara_brasil\",\"https:\/\/www.instagram.com\/compara_brasil\/\",\"https:\/\/www.linkedin.com\/company\/compara\/\",\"https:\/\/www.youtube.com\/c\/ComparaBrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\",\"name\":\"Pedro Da Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"caption\":\"Pedro Da Silva\"},\"description\":\"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.\",\"sameAs\":[\"http:\/\/usuario.ge\/nerico\"],\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primeiro carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015 - ComparaOnline","description":"O lan\u00e7amento do primeiro carro a hidrog\u00eanio foi anunciado para 2015 pela Toyota. Mas voc\u00ea sabe o que isso pode representar para o setor automotivo? Veja!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/","og_locale":"pt_BR","og_type":"article","og_title":"Primeiro carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015 - ComparaOnline","og_description":"O lan\u00e7amento do primeiro carro a hidrog\u00eanio foi anunciado para 2015 pela Toyota. Mas voc\u00ea sabe o que isso pode representar para o setor automotivo? Veja!","og_url":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/","og_site_name":"ComparaOnline","article_publisher":"https:\/\/www.facebook.com\/comparabr","article_published_time":"2014-08-25T16:17:09+00:00","article_modified_time":"2018-11-13T00:54:18+00:00","og_image":[{"width":435,"height":288,"url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/08\/104942-carro-a-hidrognio-da-toyota-ser-lanado-em-2015-1407768551.jpg","type":"image\/jpeg"}],"author":"Pedro Da Silva","twitter_card":"summary_large_image","twitter_creator":"@compara_brasil","twitter_site":"@compara_brasil","twitter_misc":{"Written by":"Pedro Da Silva","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#article","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/"},"author":{"name":"Pedro Da Silva","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f"},"headline":"Primeiro carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015","datePublished":"2014-08-25T16:17:09+00:00","dateModified":"2018-11-13T00:54:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/"},"wordCount":621,"commentCount":0,"publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/08\/104942-carro-a-hidrognio-da-toyota-ser-lanado-em-2015-1407768551.jpg","articleSection":["Carros","Seguro Auto"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/","url":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/","name":"Primeiro carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015 - ComparaOnline","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#primaryimage"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/08\/104942-carro-a-hidrognio-da-toyota-ser-lanado-em-2015-1407768551.jpg","datePublished":"2014-08-25T16:17:09+00:00","dateModified":"2018-11-13T00:54:18+00:00","description":"O lan\u00e7amento do primeiro carro a hidrog\u00eanio foi anunciado para 2015 pela Toyota. Mas voc\u00ea sabe o que isso pode representar para o setor automotivo? Veja!","breadcrumb":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#primaryimage","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/08\/104942-carro-a-hidrognio-da-toyota-ser-lanado-em-2015-1407768551.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/08\/104942-carro-a-hidrognio-da-toyota-ser-lanado-em-2015-1407768551.jpg","width":435,"height":288},{"@type":"BreadcrumbList","@id":"https:\/\/www.comparaonline.com.br\/blog\/carros\/primeiro-carro-hidrogenio-sera-lancado-em-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comparaonline.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Primeiro carro a hidrog\u00eanio ser\u00e1 lan\u00e7ado em 2015"}]},{"@type":"WebSite","@id":"https:\/\/www.comparaonline.com.br\/blog\/#website","url":"https:\/\/www.comparaonline.com.br\/blog\/","name":"ComparaOnline","description":"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros","publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization","name":"Compara","url":"https:\/\/www.comparaonline.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","width":161,"height":35,"caption":"Compara"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/comparabr","https:\/\/x.com\/compara_brasil","https:\/\/www.instagram.com\/compara_brasil\/","https:\/\/www.linkedin.com\/company\/compara\/","https:\/\/www.youtube.com\/c\/ComparaBrasil"]},{"@type":"Person","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f","name":"Pedro Da Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","caption":"Pedro Da Silva"},"description":"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.","sameAs":["http:\/\/usuario.ge\/nerico"],"url":"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/3275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3275"}],"version-history":[{"count":1,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/3275\/revisions"}],"predecessor-version":[{"id":13818,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/3275\/revisions\/13818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media\/3276"}],"wp:attachment":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}