{"id":1491,"date":"2014-02-16T18:00:03","date_gmt":"2014-02-16T18:00:03","guid":{"rendered":"http:\/\/blog.comparaonline.com.br\/?p=1491"},"modified":"2020-12-22T14:32:22","modified_gmt":"2020-12-22T17:32:22","slug":"viajar-exterior-saiba-certificado-internacional-vacinacao","status":"publish","type":"post","link":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/","title":{"rendered":"Vai viajar para o exterior? Saiba tudo sobre o certificado internacional de vacina\u00e7\u00e3o"},"content":{"rendered":"<p>Se voc\u00ea est\u00e1 se preparando para uma viagem ao exterior sabe que, al\u00e9m do visto e da contrata\u00e7\u00e3o de um seguro internacional, \u00e9 necess\u00e1rio providenciar tamb\u00e9m o CIVP <strong>(Certificado Internacional de Vacina\u00e7\u00e3o)<\/strong>. Trata-se de um documento comprobat\u00f3rio, o qual confirma que o cidad\u00e3o \u00e9 vacinado contra a febre amarela e outras doen\u00e7as.<\/p>\n<p><!--more--><\/p>\n<p>A obrigatoriedade de sua apresenta\u00e7\u00e3o \u00e9 oficializada pelo Decreto n\u00ba 87, de 15 de abril de 1991. Vale dizer ainda que, para garantir a tranquilidade durante a viagem, \u00e9 recomendada a contrata\u00e7\u00e3o de um <a title=\"Cote aqui o seu seguro viagem! \" href=\"https:\/\/www.comparaonline.com.br\/seguro-viagem\"><strong>seguro viagem<\/strong><\/a>, o qual \u00e9 respons\u00e1vel pela cobertura de poss\u00edveis gastos com atendimentos m\u00e9dicos e burocr\u00e1ticos. Mas, n\u00e3o s\u00e3o todos os destinos que exigem o certificado: para consultar os pa\u00edses que o solicitam, basta acessar a rela\u00e7\u00e3o presente no site da OMS (Organiza\u00e7\u00e3o Mundial de Sa\u00fade).<\/p>\n<p style=\"margin-bottom: 24px\">Para sanar todas as suas d\u00favidas em rela\u00e7\u00e3o ao CVIP, <strong>criamos um guia simplificado<\/strong>, abordando todo o processo.<\/p>\n<h3><strong> Aplica\u00e7\u00e3o das vacinas<\/strong><\/h3>\n<p style=\"margin-bottom: 24px\">Para receber as vacinas espec\u00edficas, como no caso da vacina contra a febre amarela, basta se dirigir \u00e0s unidades b\u00e1sicas de sa\u00fade espalhadas pelo pa\u00eds. As vacinas s\u00e3o oferecidas gratuitamente.&nbsp;Ao receb\u00ea-las, ser\u00e1 entregue o <strong>Cart\u00e3o Nacional de Vacina\u00e7\u00e3o,<\/strong> no qual constar\u00e1 a anota\u00e7\u00e3o referente \u00e0 vacina. As doses devem ser ministradas 10 dias antes da viagem e possuem validade de 10 anos.<\/p>\n<h3><strong> Solicitando o CIVP<\/strong><\/h3>\n<p>Para emitir o CIVP, o solicitante dever\u00e1 se dirigir a um dos Centros de Orienta\u00e7\u00e3o ao Viajante, localizados em portos, aeroportos e fronteiras. Para consultar os endere\u00e7os, acesse a lista disponibilizada pela <strong>Anvisa<\/strong>. A fim de agilizar o atendimento, a Anvisa recomenda que seja realizado um pr\u00e9-cadastro atrav\u00e9s de seu pr\u00f3prio site.<\/p>\n<p style=\"margin-bottom: 24px\">A solicita\u00e7\u00e3o dever\u00e1 ser realizada pessoalmente, mediante a apresenta\u00e7\u00e3o dos seguintes documentos:<br \/>\n<strong>1.<\/strong> Cart\u00e3o Nacional de Vacina\u00e7\u00e3o (preenchido com a data da administra\u00e7\u00e3o e lote da vacina, bem como identifica\u00e7\u00e3o do profissional e da unidade de sa\u00fade respons\u00e1veis).<br \/>\n<strong>2.<\/strong> Documento de identidade com foto (RG, CNH, passaporte ou carteira de trabalho). Para menores de idade, \u00e9 v\u00e1lida a apresenta\u00e7\u00e3o da Certid\u00e3o de Nascimento.<\/p>\n<h3><strong> Casos especiais de contra-indica\u00e7\u00e3o<\/strong><\/h3>\n<p>Quando o viajante n\u00e3o estiver apto a receber a vacina, dever\u00e1 obter o CIIV (Certificado de Isen\u00e7\u00e3o de Vacina\u00e7\u00e3o). Sua validade \u00e9 definida pelo m\u00e9dico que comprovou a contra-indica\u00e7\u00e3o. Esta solicita\u00e7\u00e3o tamb\u00e9m \u00e9 realizada atrav\u00e9s dos Centros de Orienta\u00e7\u00e3o ao Viajante da Anvisa, mediante a apresenta\u00e7\u00e3o dos seguintes documentos:<\/p>\n<p><strong>1.<\/strong> Documento de identidade com foto (RG, CNH, passaporte ou carteira de trabalho). Neste caso, para menores de idade tamb\u00e9m \u00e9 v\u00e1lida a apresenta\u00e7\u00e3o da Certid\u00e3o de Nascimento.<\/p>\n<p style=\"margin-bottom: 24px\"><strong>2.<\/strong> Atestado m\u00e9dico com o motivo da contra-indica\u00e7\u00e3o. No documento dever\u00e3o constar o nome do viajante, carimbo e assinatura do m\u00e9dico, n\u00famero do CRM e identifica\u00e7\u00e3o completa do consult\u00f3rio.<\/p>\n<p>Alguns pacotes j\u00e1 contam com planos b\u00e1sicos de seguro viagem&nbsp;<a title=\"Solicite aqui o seu seguro viagem! \" href=\"https:\/\/www.comparaonline.com.br\/seguro-viagem\">&nbsp;<\/a><strong><a title=\"Solicite aqui o seu seguro viagem! \" href=\"https:\/\/www.comparaonline.com.br\/seguro-viagem\">seguro viagem<\/a>.<\/strong>&nbsp;Entretanto, garantir uma cobertura completa, principalmente quando acompanhado das crian\u00e7as, \u00e9 altamente indicado!<\/p>\n<p>&nbsp;<\/p>\n<p>Leia mais sobre o assunto:<\/p>\n<p>https:\/\/www.comparaonline.com.br\/blog\/seguros\/2017\/05\/carteira-internacional-de-vacinacao-saiba-quais-sao-vacinas-exigidas\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se voc\u00ea est\u00e1 se preparando para uma viagem ao exterior sabe que, al\u00e9m do visto e da contrata\u00e7\u00e3o de um seguro internacional, \u00e9 necess\u00e1rio providenciar tamb\u00e9m o CIVP (Certificado Internacional de Vacina\u00e7\u00e3o). Trata-se de um documento comprobat\u00f3rio, o qual confirma que o cidad\u00e3o \u00e9 vacinado contra a febre amarela e outras doen\u00e7as.<\/p>\n","protected":false},"author":15,"featured_media":1492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[716],"tags":[],"class_list":["post-1491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viagem"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vai viajar? Verifique o certificado internacional de vacina\u00e7\u00e3o | Compara BR<\/title>\n<meta name=\"description\" content=\"Vai viajar pra fora do Brasil e n\u00e3o sabe se precisa tomar vacina antes de embarcar? Compara fez uma guia com os passos a seguir, veja!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vai viajar? Verifique o certificado internacional de vacina\u00e7\u00e3o | Compara BR\" \/>\n<meta property=\"og:description\" content=\"Vai viajar pra fora do Brasil e n\u00e3o sabe se precisa tomar vacina antes de embarcar? Compara fez uma guia com os passos a seguir, veja!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/\" \/>\n<meta property=\"og:site_name\" content=\"ComparaOnline\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/comparabr\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-16T18:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-22T17:32:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/02\/78025-vai-viajar-para-o-exterior-saiba-tudo-sobre-o-certificado-internacional-de-vacina-ccedil-atilde-o-1391449769.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"435\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pedro Da Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:site\" content=\"@compara_brasil\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Da Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/\"},\"author\":{\"name\":\"Pedro Da Silva\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\"},\"headline\":\"Vai viajar para o exterior? Saiba tudo sobre o certificado internacional de vacina\u00e7\u00e3o\",\"datePublished\":\"2014-02-16T18:00:03+00:00\",\"dateModified\":\"2020-12-22T17:32:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/\"},\"wordCount\":751,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/02\/78025-vai-viajar-para-o-exterior-saiba-tudo-sobre-o-certificado-internacional-de-vacina-ccedil-atilde-o-1391449769.jpg\",\"articleSection\":[\"Viagem\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/\",\"name\":\"Vai viajar? Verifique o certificado internacional de vacina\u00e7\u00e3o | Compara BR\",\"isPartOf\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/02\/78025-vai-viajar-para-o-exterior-saiba-tudo-sobre-o-certificado-internacional-de-vacina-ccedil-atilde-o-1391449769.jpg\",\"datePublished\":\"2014-02-16T18:00:03+00:00\",\"dateModified\":\"2020-12-22T17:32:22+00:00\",\"description\":\"Vai viajar pra fora do Brasil e n\u00e3o sabe se precisa tomar vacina antes de embarcar? Compara fez uma guia com os passos a seguir, veja!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#primaryimage\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/02\/78025-vai-viajar-para-o-exterior-saiba-tudo-sobre-o-certificado-internacional-de-vacina-ccedil-atilde-o-1391449769.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/02\/78025-vai-viajar-para-o-exterior-saiba-tudo-sobre-o-certificado-internacional-de-vacina-ccedil-atilde-o-1391449769.jpg\",\"width\":435,\"height\":288,\"caption\":\"A Organiza\u00e7\u00e3o Mundial da Sa\u00fade divulga a lista de destinos que exigem vacinas para entrar ao pa\u00eds\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.comparaonline.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vai viajar para o exterior? Saiba tudo sobre o certificado internacional de vacina\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#website\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"name\":\"ComparaOnline\",\"description\":\"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros\",\"publisher\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#organization\",\"name\":\"Compara\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png\",\"width\":161,\"height\":35,\"caption\":\"Compara\"},\"image\":{\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/comparabr\",\"https:\/\/x.com\/compara_brasil\",\"https:\/\/www.instagram.com\/compara_brasil\/\",\"https:\/\/www.linkedin.com\/company\/compara\/\",\"https:\/\/www.youtube.com\/c\/ComparaBrasil\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f\",\"name\":\"Pedro Da Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"contentUrl\":\"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg\",\"caption\":\"Pedro Da Silva\"},\"description\":\"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.\",\"sameAs\":[\"http:\/\/usuario.ge\/nerico\"],\"url\":\"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vai viajar? Verifique o certificado internacional de vacina\u00e7\u00e3o | Compara BR","description":"Vai viajar pra fora do Brasil e n\u00e3o sabe se precisa tomar vacina antes de embarcar? Compara fez uma guia com os passos a seguir, veja!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Vai viajar? Verifique o certificado internacional de vacina\u00e7\u00e3o | Compara BR","og_description":"Vai viajar pra fora do Brasil e n\u00e3o sabe se precisa tomar vacina antes de embarcar? Compara fez uma guia com os passos a seguir, veja!","og_url":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/","og_site_name":"ComparaOnline","article_publisher":"https:\/\/www.facebook.com\/comparabr","article_published_time":"2014-02-16T18:00:03+00:00","article_modified_time":"2020-12-22T17:32:22+00:00","og_image":[{"width":435,"height":288,"url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/02\/78025-vai-viajar-para-o-exterior-saiba-tudo-sobre-o-certificado-internacional-de-vacina-ccedil-atilde-o-1391449769.jpg","type":"image\/jpeg"}],"author":"Pedro Da Silva","twitter_card":"summary_large_image","twitter_creator":"@compara_brasil","twitter_site":"@compara_brasil","twitter_misc":{"Escrito por":"Pedro Da Silva","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#article","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/"},"author":{"name":"Pedro Da Silva","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f"},"headline":"Vai viajar para o exterior? Saiba tudo sobre o certificado internacional de vacina\u00e7\u00e3o","datePublished":"2014-02-16T18:00:03+00:00","dateModified":"2020-12-22T17:32:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/"},"wordCount":751,"commentCount":0,"publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/02\/78025-vai-viajar-para-o-exterior-saiba-tudo-sobre-o-certificado-internacional-de-vacina-ccedil-atilde-o-1391449769.jpg","articleSection":["Viagem"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/","url":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/","name":"Vai viajar? Verifique o certificado internacional de vacina\u00e7\u00e3o | Compara BR","isPartOf":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#primaryimage"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/02\/78025-vai-viajar-para-o-exterior-saiba-tudo-sobre-o-certificado-internacional-de-vacina-ccedil-atilde-o-1391449769.jpg","datePublished":"2014-02-16T18:00:03+00:00","dateModified":"2020-12-22T17:32:22+00:00","description":"Vai viajar pra fora do Brasil e n\u00e3o sabe se precisa tomar vacina antes de embarcar? Compara fez uma guia com os passos a seguir, veja!","breadcrumb":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#primaryimage","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/02\/78025-vai-viajar-para-o-exterior-saiba-tudo-sobre-o-certificado-internacional-de-vacina-ccedil-atilde-o-1391449769.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2014\/02\/78025-vai-viajar-para-o-exterior-saiba-tudo-sobre-o-certificado-internacional-de-vacina-ccedil-atilde-o-1391449769.jpg","width":435,"height":288,"caption":"A Organiza\u00e7\u00e3o Mundial da Sa\u00fade divulga a lista de destinos que exigem vacinas para entrar ao pa\u00eds"},{"@type":"BreadcrumbList","@id":"https:\/\/www.comparaonline.com.br\/blog\/viagem\/viajar-exterior-saiba-certificado-internacional-vacinacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.comparaonline.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Vai viajar para o exterior? Saiba tudo sobre o certificado internacional de vacina\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/www.comparaonline.com.br\/blog\/#website","url":"https:\/\/www.comparaonline.com.br\/blog\/","name":"ComparaOnline","description":"Tudo o que voc\u00ea precisa saber sobre seguros e produtos financeiros","publisher":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.comparaonline.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.comparaonline.com.br\/blog\/#organization","name":"Compara","url":"https:\/\/www.comparaonline.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/15814375758341.png","width":161,"height":35,"caption":"Compara"},"image":{"@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/comparabr","https:\/\/x.com\/compara_brasil","https:\/\/www.instagram.com\/compara_brasil\/","https:\/\/www.linkedin.com\/company\/compara\/","https:\/\/www.youtube.com\/c\/ComparaBrasil"]},{"@type":"Person","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/927a0adda400e42e5095e98c5fbd0f8f","name":"Pedro Da Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.comparaonline.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","contentUrl":"https:\/\/www.comparaonline.com.br\/blog-statics\/br\/uploads\/2020\/02\/Pedro-Da-Silva.jpg","caption":"Pedro Da Silva"},"description":"Sou formado em comunica\u00e7\u00e3o social, especializado em finan\u00e7as e seguros. Como essas s\u00e3o quest\u00f5es muitas vezes confusas ou dif\u00edcais de entender, gosto de explic\u00e1-las de uma maneira simples e divertida.","sameAs":["http:\/\/usuario.ge\/nerico"],"url":"https:\/\/www.comparaonline.com.br\/blog\/author\/pedro-da-silva\/"}]}},"_links":{"self":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/1491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1491"}],"version-history":[{"count":3,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/1491\/revisions"}],"predecessor-version":[{"id":18887,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/1491\/revisions\/18887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media\/1492"}],"wp:attachment":[{"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comparaonline.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}